{"id":136915,"date":"2025-11-14T21:18:36","date_gmt":"2025-11-14T20:18:36","guid":{"rendered":"https:\/\/sequiol.es\/?p=136915"},"modified":"2025-12-30T21:20:46","modified_gmt":"2025-12-30T20:20:46","slug":"cartel-anunciador-de-la-magdalena-2026","status":"publish","type":"post","link":"https:\/\/sequiol.es\/es\/cartel-anunciador-de-la-magdalena-2026\/","title":{"rendered":"Cartel anunciador de la Magdalena 2026"},"content":{"rendered":"<p>El cartel anunciador constituye uno de los elementos esenciales de cada edici\u00f3n de la Magdalena. Este a\u00f1o se recuper\u00f3 el formato tradicional de elecci\u00f3n, abriendo la convocatoria a todas las personas interesadas en presentar sus propuestas. La respuesta fue muy positiva, con un total de sesenta y tres trabajos recibidos.<\/p>\n<p>El viernes 14 de noviembre, el Menador acogi\u00f3 al M\u00f3n de la Festa para dar a conocer el cartel ganador, que ser\u00e1 la imagen oficial de la Magdalena 2026. La lectura del acta del jurado revel\u00f3 que el cartel seleccionado llevaba por lema \u201cMonumental\u201d. Tras abrir la plica correspondiente, se conoci\u00f3 la autor\u00eda:<br \/>\nJuan Diego Ingelmo, dise\u00f1ador gr\u00e1fico y cartelista, quien ya hab\u00eda obtenido este reconocimiento en las ediciones de 2009, 2011 y 2014. Fue la propia alcaldesa de la ciudad quien comunic\u00f3 telef\u00f3nicamente el fallo al autor.<\/p>\n<p>La obra, en la que predomina el color verde y la Gaiata como s\u00edmbolo central, integra diversos elementos representativos de la fiesta y de la ciudad.<\/p>\n<p>La Gaiata 15 Sequiol estuvo presente en el acto, y nuestras madrinas Vega Peraire y Mar\u00eda Collados, junto con la presidenta Elisabeth Breva, inmortalizaron el momento posando junto al cartel ganador.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El cartel anunciador constituye uno de los elementos esenciales de cada edici\u00f3n de la Magdalena. Este a\u00f1o se recuper\u00f3 el formato tradicional de elecci\u00f3n, abriendo la convocatoria a todas las personas interesadas en presentar sus propuestas. La respuesta fue muy positiva, con un total de sesenta y tres trabajos recibidos. El viernes 14 de noviembre, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":136911,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[179],"tags":[],"class_list":["post-136915","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-magdalena-2026"],"_links":{"self":[{"href":"https:\/\/sequiol.es\/es\/wp-json\/wp\/v2\/posts\/136915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sequiol.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sequiol.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sequiol.es\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sequiol.es\/es\/wp-json\/wp\/v2\/comments?post=136915"}],"version-history":[{"count":1,"href":"https:\/\/sequiol.es\/es\/wp-json\/wp\/v2\/posts\/136915\/revisions"}],"predecessor-version":[{"id":136916,"href":"https:\/\/sequiol.es\/es\/wp-json\/wp\/v2\/posts\/136915\/revisions\/136916"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sequiol.es\/es\/wp-json\/wp\/v2\/media\/136911"}],"wp:attachment":[{"href":"https:\/\/sequiol.es\/es\/wp-json\/wp\/v2\/media?parent=136915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sequiol.es\/es\/wp-json\/wp\/v2\/categories?post=136915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sequiol.es\/es\/wp-json\/wp\/v2\/tags?post=136915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}