{"id":27752,"date":"2016-12-19T20:07:10","date_gmt":"2016-12-19T19:07:10","guid":{"rendered":"http:\/\/sequiol.es\/?p=27752\/"},"modified":"2017-01-28T18:37:18","modified_gmt":"2017-01-28T17:37:18","slug":"2017-life-belen-from-the-gaiateros-artist-asociation","status":"publish","type":"post","link":"https:\/\/sequiol.es\/en\/2017-life-belen-from-the-gaiateros-artist-asociation\/","title":{"rendered":"Life Bel\u00e9n from the Gaiateros&#8217; artist asociation"},"content":{"rendered":"<p>Last Sunday 18th of december altough it was rainning we could make th life Belen in the Paseo Ribalta that is was designed for this event by the Gaiateros&#8217;artist asociation. Pepin Marco its president was dreamingwith this idea years ago and then this year it could be possible to do it, thanks by his idea and the help from the gaiatas and lots of people that want this idea could be truth so they want to give some protagonism to this special act.<\/p>\n<p>Altough the rainy day this act was special ,only make shorter than we wanted it. The Paseo central of the Park it was comimg plenty of the biblic stories and very christmas one, the Portal de Bel\u00e9n, people working as it was suposed they did it in that time with the wood, washing the clothes as it was in that year and of course Mariah, Jesus and Saint Joseph, also they appear the three wise men, they were dressed with the clothes it was suppposed in that time, those clothes were fom the gaiata 15 th Sequiol, also this gaiata made lots of work and went lots of nice Pajes and they let lots of clothes for all the people that were there.<\/p>\n<p>There were of course our representative Bea, Teresa, and Marcos, and our president Elisabeth, giving all their support for this new iniciative that we think it is going to repeat next years .<\/p>\n<div id=\"muphy\" class=\"galeria-diapositivas\">\r\n\t<div class=\"slideshow_container slideshow_container_style-light\" style=\"height: 400px; \" data-slideshow-id=\"26812\" data-style-name=\"style-light\" data-style-version=\"2.3.1\" >\r\n\r\n\t\t\t\t\t<div class=\"slideshow_loading_icon\"><\/div>\r\n\t\t\r\n\t\t<div class=\"slideshow_content\" style=\"display: none;\">\r\n\r\n\t\t\t<div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/sequiol.es\/wp-content\/uploads\/2016\/12\/161218-belen-viviente-9614.jpg\" alt=\"161218-belen-viviente-9614\" width=\"1600\" height=\"898\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">161218-belen-viviente-9614<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/sequiol.es\/wp-content\/uploads\/2016\/12\/161218-belen-viviente-9617.jpg\" alt=\"161218-belen-viviente-9617\" width=\"1600\" height=\"898\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">161218-belen-viviente-9617<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/sequiol.es\/wp-content\/uploads\/2016\/12\/161218-belen-viviente-9616.jpg\" alt=\"161218-belen-viviente-9616\" width=\"1600\" height=\"898\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">161218-belen-viviente-9616<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/sequiol.es\/wp-content\/uploads\/2016\/12\/161218-belen-viviente-9615.jpg\" alt=\"161218-belen-viviente-9615\" width=\"1600\" height=\"898\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">161218-belen-viviente-9615<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/sequiol.es\/wp-content\/uploads\/2016\/12\/161218-belen-viviente-9658.jpg\" alt=\"161218-belen-viviente-9658\" width=\"1600\" height=\"1200\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">161218-belen-viviente-9658<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/sequiol.es\/wp-content\/uploads\/2016\/12\/161218-belen-viviente-9657.jpg\" alt=\"161218-belen-viviente-9657\" width=\"1600\" height=\"1200\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">161218-belen-viviente-9657<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/sequiol.es\/wp-content\/uploads\/2016\/12\/161218-belen-viviente-9654.jpg\" alt=\"161218-belen-viviente-9654\" width=\"886\" height=\"591\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">161218-belen-viviente-9654<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/sequiol.es\/wp-content\/uploads\/2016\/12\/161218-belen-viviente-9666.jpg\" alt=\"161218-belen-viviente-9666\" width=\"1600\" height=\"1200\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">161218-belen-viviente-9666<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/sequiol.es\/wp-content\/uploads\/2016\/12\/161218-belen-viviente-9665.jpg\" alt=\"161218-belen-viviente-9665\" width=\"1600\" height=\"1200\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">161218-belen-viviente-9665<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/sequiol.es\/wp-content\/uploads\/2016\/12\/161218-belen-vviente-9664.jpg\" alt=\"161218-belen-vviente-9664\" width=\"1600\" height=\"1200\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">161218-belen-vviente-9664<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/sequiol.es\/wp-content\/uploads\/2016\/12\/161218-belen-viviente-9663.jpg\" alt=\"161218-belen-viviente-9663\" width=\"1600\" height=\"1200\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">161218-belen-viviente-9663<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/sequiol.es\/wp-content\/uploads\/2016\/12\/161218-belen-viviente-9662.jpg\" alt=\"161218-belen-viviente-9662\" width=\"1600\" height=\"1200\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">161218-belen-viviente-9662<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/sequiol.es\/wp-content\/uploads\/2016\/12\/161218-belen-viviente-9661.jpg\" alt=\"161218-belen-viviente-9661\" width=\"1600\" height=\"1200\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">161218-belen-viviente-9661<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/sequiol.es\/wp-content\/uploads\/2016\/12\/161218-belen-viviente-9660.jpg\" alt=\"161218-belen-viviente-9660\" width=\"1600\" height=\"1200\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">161218-belen-viviente-9660<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/sequiol.es\/wp-content\/uploads\/2016\/12\/161218-belen-viviente-9659.jpg\" alt=\"161218-belen-viviente-9659\" width=\"1600\" height=\"1200\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">161218-belen-viviente-9659<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/sequiol.es\/wp-content\/uploads\/2016\/12\/161216-belen-vivienter-9636.jpg\" alt=\"161216-belen-vivienter-9636\" width=\"1024\" height=\"768\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">161216-belen-vivienter-9636<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/sequiol.es\/wp-content\/uploads\/2016\/12\/161216-belen-vivienter-9633.jpg\" alt=\"161216-belen-vivienter-9633\" width=\"1024\" height=\"768\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">161216-belen-vivienter-9633<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/sequiol.es\/wp-content\/uploads\/2016\/12\/161216-belen-vivienter-9632.jpg\" alt=\"161216-belen-vivienter-9632\" width=\"1024\" height=\"768\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">161216-belen-vivienter-9632<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/sequiol.es\/wp-content\/uploads\/2016\/12\/161218-belen-vivienter-9623.jpg\" alt=\"161218-belen-vivienter-9623\" width=\"1024\" height=\"768\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">161218-belen-vivienter-9623<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/sequiol.es\/wp-content\/uploads\/2016\/12\/161218-belen-vivienter-9620.jpg\" alt=\"161218-belen-vivienter-9620\" width=\"1024\" height=\"768\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">161218-belen-vivienter-9620<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/sequiol.es\/wp-content\/uploads\/2016\/12\/161218-belen-vivienter-9641.jpg\" alt=\"161218-belen-vivienter-9641\" width=\"768\" height=\"1024\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">161218-belen-vivienter-9641<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/sequiol.es\/wp-content\/uploads\/2016\/12\/161216-belen-vivienter-9640.jpg\" alt=\"161216-belen-vivienter-9640\" width=\"1024\" height=\"768\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">161216-belen-vivienter-9640<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/sequiol.es\/wp-content\/uploads\/2016\/12\/161216-belen-vivienter-9637.jpg\" alt=\"161216-belen-vivienter-9637\" width=\"1024\" height=\"768\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">161216-belen-vivienter-9637<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div>\r\n\t\t<\/div>\r\n\r\n\t\t<div class=\"slideshow_controlPanel slideshow_transparent\" style=\"display: none;\"><ul><li class=\"slideshow_togglePlay\" data-play-text=\"Play\" data-pause-text=\"Pause\"><\/li><\/ul><\/div>\r\n\r\n\t\t<div class=\"slideshow_button slideshow_previous slideshow_transparent\" role=\"button\" data-previous-text=\"Previous\" style=\"display: none;\"><\/div>\r\n\t\t<div class=\"slideshow_button slideshow_next slideshow_transparent\" role=\"button\" data-next-text=\"Next\" style=\"display: none;\"><\/div>\r\n\r\n\t\t<div class=\"slideshow_pagination\" style=\"display: none;\" data-go-to-text=\"Go to slide\"><div class=\"slideshow_pagination_center\"><\/div><\/div>\r\n\r\n\t\t<!-- WordPress Slideshow Version 2.3.1 -->\r\n\r\n\t\t\t<\/div>\r\n\r\n<\/div>\n<p style=\"text-align: center;\"><small>Photos courtesy of <a title=\"Ediciones Digitales Muphy\" href=\"http:\/\/edimuphy.com\" target=\"_blank\">Ediciones Digitales Muphy<\/a><\/small><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Last Sunday 18th of december altough it was rainning we could make th life Belen in the Paseo Ribalta that is was designed for this event by the Gaiateros&#8217;artist asociation. Pepin Marco its president was dreamingwith this idea years ago and then this year it could be possible to do it, thanks by his idea [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":27753,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[111],"tags":[],"class_list":["post-27752","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-magdalena-2017-en"],"_links":{"self":[{"href":"https:\/\/sequiol.es\/en\/wp-json\/wp\/v2\/posts\/27752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sequiol.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sequiol.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sequiol.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sequiol.es\/en\/wp-json\/wp\/v2\/comments?post=27752"}],"version-history":[{"count":1,"href":"https:\/\/sequiol.es\/en\/wp-json\/wp\/v2\/posts\/27752\/revisions"}],"predecessor-version":[{"id":27754,"href":"https:\/\/sequiol.es\/en\/wp-json\/wp\/v2\/posts\/27752\/revisions\/27754"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sequiol.es\/en\/wp-json\/wp\/v2\/media\/27753"}],"wp:attachment":[{"href":"https:\/\/sequiol.es\/en\/wp-json\/wp\/v2\/media?parent=27752"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sequiol.es\/en\/wp-json\/wp\/v2\/categories?post=27752"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sequiol.es\/en\/wp-json\/wp\/v2\/tags?post=27752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}